{"id":29,"count":2,"description":"","link":"https:\/\/rva-marketing.com\/es\/category\/design\/","name":"Dise\u00f1o","slug":"design","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/rva-marketing.com\/es\/wp-json\/wp\/v2\/categories\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rva-marketing.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/rva-marketing.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/rva-marketing.com\/es\/wp-json\/wp\/v2\/posts?categories=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}